{"id":962,"date":"2008-03-21T22:30:46","date_gmt":"2008-03-21T20:30:46","guid":{"rendered":"http:\/\/www.sashs-blog.de\/wordpress\/?p=962"},"modified":"2012-10-08T03:44:15","modified_gmt":"2012-10-08T01:44:15","slug":"c18h27no3","status":"publish","type":"post","link":"https:\/\/www.sashs-blog.de\/wordpress\/2008\/03\/21\/c18h27no3\/","title":{"rendered":"C18H27NO3"},"content":{"rendered":"<p style=\"text-align: justify;\">Ich muss irgendwie noch einmal zum gestrigen Thema zur\u00fcckkehren: Ich bin gerade hocherfreut dar\u00fcber, dass auch meine Freundin sich langsam dem scharfen Essen zuwendet. Na gut, ich bin nicht alleine daran schuld, und zudem reizt sie der Anbau von Pflanzen allgemein. Die bei uns nun wachsenden Chilis haben also ihren Ursprung nicht unbedingt in meiner Liebe zur Sch\u00e4rfe.<\/p>\n<p style=\"text-align: justify;\">Wer sich noch fragt, was die \u00dcberschrift zu bedeuten hat, der sei &#8211; ohne bei Wikipedia schauen zu m\u00fcssen &#8211; hiermit aufgekl\u00e4rt: Es ist die chemische Formel f\u00fcr Capsaicin, jenem Stoff, der meinen Lieblingspflanzen die n\u00f6tige W\u00fcrze verleiht, und zudem im Falle einer Extremsituation daf\u00fcr verantwortlich ist, dass ich vor der Polizei nicht mehr fliehen kann (Pfefferspray).<\/p>\n<p style=\"text-align: justify;\">Aber Capsaicin ist ein recht positiver Stoff, der nicht nur Schmerzrezeptoren reizen kann, damit man Chilis als feurig empfindet. Er findet auch Anwendung auf W\u00e4rmepflastern und kann zumindest bei M\u00e4usen zu einer Bremse f\u00fcr Prostatakrebs werden. Desweiteren h\u00e4lt er Bakterien und Pilze fern &#8211; allerdings keine Motten! Die Erfahrung haben wir in unserer WG vor langer Zeit schon gemacht. Auch wenn man es nicht glauben will &#8211; Lebensmittelmotten nisten sich auch in getrockneten Chilis ein. Die Schweine!<\/p>\n<p style=\"text-align: justify;\">Die Vermutung, dass eine &#8222;leichte Sucht&#8220; nach scharfen Speisen entwickelt werden kann, kann ich nur zustimmen. Ich denke aber, dass es &#8211; sofern man den Magen seiner G\u00e4ste nicht \u00fcberm\u00e4\u00dfig strapaziert &#8211; weitaus schlimmere S\u00fcchte als die diese gibt.<\/p>\n<p style=\"text-align: justify;\">Ich bin sicher (noch) kein &#8222;Chilihead&#8220;, wie er auf vielen einschl\u00e4gigen Seiten beschworen wird, aber ich muss meine Liebe zu herzhaftem Essen mit einem Hang zu h\u00f6heren Stufen auf der Scoville-Skala eingestehen. &#8222;Pain is good&#8220;, wahrscheinlich das tragende Leitmotto der Bewegung, mag ich nur zum Teil tragen, aber ja: Ich kenne das Gef\u00fchl, das dahintersteht, und das sehr gut.<\/p>\n<p style=\"text-align: justify;\">Ich hoffe stark, dass die Habaneros im Zimmer von Ozie ordentlich reifen m\u00f6gen, und ich auch in Zukunft noch viel Spa\u00df mit meinem Freund Capsaicin habe. Ich weiss, dass mich bei weitem nicht jeder versteht, aber das ist ok. Wer keine Chilis mag, der kann seine gerne an mich spenden \ud83d\ude09<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ich muss irgendwie noch einmal zum gestrigen Thema zur\u00fcckkehren: Ich bin gerade hocherfreut dar\u00fcber, dass auch meine Freundin sich langsam dem scharfen Essen zuwendet. Na gut, ich bin nicht alleine daran schuld, und zudem reizt sie der Anbau von Pflanzen &hellip; <a href=\"https:\/\/www.sashs-blog.de\/wordpress\/2008\/03\/21\/c18h27no3\/\">Continue reading <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_editorskit_title_hidden":false,"_editorskit_reading_time":0,"_editorskit_is_block_options_detached":false,"_editorskit_block_options_position":"{}","footnotes":""},"categories":[12,1],"tags":[],"class_list":["post-962","post","type-post","status-publish","format-standard","hentry","category-haushalt","category-vermischtes"],"_links":{"self":[{"href":"https:\/\/www.sashs-blog.de\/wordpress\/wp-json\/wp\/v2\/posts\/962","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.sashs-blog.de\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sashs-blog.de\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sashs-blog.de\/wordpress\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sashs-blog.de\/wordpress\/wp-json\/wp\/v2\/comments?post=962"}],"version-history":[{"count":3,"href":"https:\/\/www.sashs-blog.de\/wordpress\/wp-json\/wp\/v2\/posts\/962\/revisions"}],"predecessor-version":[{"id":12463,"href":"https:\/\/www.sashs-blog.de\/wordpress\/wp-json\/wp\/v2\/posts\/962\/revisions\/12463"}],"wp:attachment":[{"href":"https:\/\/www.sashs-blog.de\/wordpress\/wp-json\/wp\/v2\/media?parent=962"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sashs-blog.de\/wordpress\/wp-json\/wp\/v2\/categories?post=962"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sashs-blog.de\/wordpress\/wp-json\/wp\/v2\/tags?post=962"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}