{"id":341,"date":"2008-12-01T17:50:22","date_gmt":"2008-12-01T16:50:22","guid":{"rendered":"http:\/\/www.sashs-blog.de\/wordpress\/?p=341"},"modified":"2012-03-19T01:26:54","modified_gmt":"2012-03-18T23:26:54","slug":"welt-aids-tag","status":"publish","type":"post","link":"https:\/\/www.sashs-blog.de\/wordpress\/2008\/12\/01\/welt-aids-tag\/","title":{"rendered":"Welt-AIDS-Tag"},"content":{"rendered":"<p style=\"text-align: justify;\">Heute ist Welt-Aids-Tag, und von meiner Seite aus ein ernst gemeintes Beileid an alle Betroffenen! Es sind so viele Jahre ins Land gezogen, seit Aids bekannt ist. Traurigerweise liest und h\u00f6rt man in der vergangenen Zeit immer wieder davon, dass es gerade jetzt um die Aufkl\u00e4rung schlecht bestimmt ist. Ich weiss das nicht einzusch\u00e4tzen, denn meine Kindheit und Pubert\u00e4t ist stark beeinflusst von dem &#8222;Hype&#8220; um Aids. Inzwischen scheint das Bewusstsein daf\u00fcr nachzulassen &#8211; zumindest hierzulande &#8211; was mich ein wenig erschaudern l\u00e4sst.<\/p>\n<p style=\"text-align: justify;\">Zwar kann man eine Infektion eigentlich recht gut verhindern, aber das heisst noch lange nicht, dass man nicht solidarisch sein sollte mit den Leuten, die einen Fehler gemacht haben. Aber: Was der gesunde Menschenverstand gebietet, <a href=\"http:\/\/www.bildblog.de\/4101\/bildde-beweist-welt-aids-tag-immer-noch-noetig\/\">gilt nat\u00fcrlich noch lange nicht f\u00fcr bild.de<\/a>. Kotz!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Heute ist Welt-Aids-Tag, und von meiner Seite aus ein ernst gemeintes Beileid an alle Betroffenen! Es sind so viele Jahre ins Land gezogen, seit Aids bekannt ist. Traurigerweise liest und h\u00f6rt man in der vergangenen Zeit immer wieder davon, dass &hellip; <a href=\"https:\/\/www.sashs-blog.de\/wordpress\/2008\/12\/01\/welt-aids-tag\/\">Continue reading <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_editorskit_title_hidden":false,"_editorskit_reading_time":0,"_editorskit_is_block_options_detached":false,"_editorskit_block_options_position":"{}","footnotes":""},"categories":[7,1],"tags":[],"class_list":["post-341","post","type-post","status-publish","format-standard","hentry","category-medien","category-vermischtes"],"_links":{"self":[{"href":"https:\/\/www.sashs-blog.de\/wordpress\/wp-json\/wp\/v2\/posts\/341","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.sashs-blog.de\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sashs-blog.de\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sashs-blog.de\/wordpress\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sashs-blog.de\/wordpress\/wp-json\/wp\/v2\/comments?post=341"}],"version-history":[{"count":4,"href":"https:\/\/www.sashs-blog.de\/wordpress\/wp-json\/wp\/v2\/posts\/341\/revisions"}],"predecessor-version":[{"id":11669,"href":"https:\/\/www.sashs-blog.de\/wordpress\/wp-json\/wp\/v2\/posts\/341\/revisions\/11669"}],"wp:attachment":[{"href":"https:\/\/www.sashs-blog.de\/wordpress\/wp-json\/wp\/v2\/media?parent=341"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sashs-blog.de\/wordpress\/wp-json\/wp\/v2\/categories?post=341"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sashs-blog.de\/wordpress\/wp-json\/wp\/v2\/tags?post=341"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}